{"id":229,"count":7,"description":"","link":"https:\/\/envasesyempaqueselixir.com\/index.php\/categoria-producto\/oulet\/","name":"Oulet","slug":"oulet","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/envasesyempaqueselixir.com\/index.php\/wp-json\/wp\/v2\/product_cat\/229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/envasesyempaqueselixir.com\/index.php\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/envasesyempaqueselixir.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/envasesyempaqueselixir.com\/index.php\/wp-json\/wp\/v2\/product?product_cat=229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}